{"id":2180,"date":"2020-03-30T12:43:25","date_gmt":"2020-03-30T10:43:25","guid":{"rendered":"https:\/\/www.fabivt.it\/wp\/?p=2180"},"modified":"2020-04-26T15:08:51","modified_gmt":"2020-04-26T13:08:51","slug":"decreto-cura-italia-del-17-marzo-2020-n-18","status":"publish","type":"post","link":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/","title":{"rendered":"Decreto Cura Italia del 17 marzo 2020, n.18"},"content":{"rendered":"<p>Il decreto legge 17 marzo 2020, n. 18, cosiddetto \u201c<strong>Cura Italia<\/strong>\u201d, ha previso <strong>misure di sostegno<\/strong> alle <strong>famiglie<\/strong> e ai <strong>lavoratori<\/strong>, connesse all\u2019emergenza epidemiologica COVID -19.L\u2019articolo 23 del d.l. 18\/2020 ha introdotto un <strong>congedo indennizzato<\/strong> per la cura dei minori. Possono fruire del congedo i genitori lavoratori dipendenti privati, lavoratori iscritti alla Gestione Separata, lavoratori autonomi iscritti all\u2019INPS e lavoratori dipendenti pubblici. Inoltre, l\u2019articolo 24 del d.l. 18\/2020 ha previsto l\u2019incremento del numero di giorni di permesso retribuiti stabiliti dall\u2019articolo 33, della legge 5 febbraio 1992, n. 104, di ulteriori complessive <strong>12 giornate<\/strong> usufruibili nei mesi di marzo e aprile 2020.La <a class=\"NormSott\" title=\"Vai alla circolare\" href=\"https:\/\/www.inps.it\/nuovoportaleinps\/default.aspx?sPathID=%3b0%3b52983%3b&amp;lastMenu=52983&amp;iMenu=1&amp;sURL=https%3a%2f%2fwww.inps.it%2fbussola%2fVisualizzaDoc.aspx%3fsVirtualURL%3d%252fCircolari%252fCircolare%2520numero%252045%2520del%252025-03-2020.htm&amp;RedirectForzato=True\" target=\"_blank\" rel=\"noopener noreferrer\">circolare INPS 25 marzo 2020, n. 45<\/a> fornisce le istruzioni operative per la fruizione dei congedi parentali e dei permessi retribuiti. Vengono fornite, inoltre, le indicazioni sulla compilazione delle denunce contributive per i datori di lavoro.<\/p>\n<p>In alternativa al congedo, con la <a title=\"Vai alla circolare\" href=\"https:\/\/www.inps.it\/nuovoportaleinps\/default.aspx?sPathID=%3b0%3b52983%3b&amp;lastMenu=52983&amp;iMenu=1&amp;sURL=https%3a%2f%2fwww.inps.it%2fnuovoportaleinps%2fdefault.aspx%3fsPathID%3d%253b0%253b52969%253b%26lastMenu%3d52969%26iMenu%3d1%26sURL%3dhttps%253a%252f%252fwww.inps.it%252fbussola%252fVisualizzaDoc.aspx%253fsVirtualURL%253d%25252fCircolari%25252fCircolare%252520numero%25252044%252520del%25252024-03-2020.htm%26RedirectForzato%3dTrue&amp;RedirectForzato=True\" target=\"_blank\" rel=\"noopener noreferrer\">circolare INPS 24 marzo 2020, n. 44<\/a>, \u00e8 stata prevista la possibilit\u00e0 per i genitori di richiedere un bonus per l\u2019acquisto di <strong>servizi di baby-sitting <\/strong>nel limite massimo di <strong>600 euro<\/strong>. La circolare fornisce le indicazioni in merito ai\u00a0<strong>requisiti<\/strong>, alla\u00a0<strong>misura del beneficio<\/strong>, alle\u00a0<strong>modalit\u00e0 di compilazione della domanda<\/strong>\u00a0e all\u2019erogazione del bonus.<\/p>\n<p>I destinatari di questa misura sono i dipendenti privati, gli iscritti alla Gestione Separata e i lavoratori autonomi. L\u2019articolo 25 del d.l. 18\/2020 estende anche ai <strong>dipendenti del settore pubblico<\/strong> le medesime agevolazioni previste per le famiglie del settore privato. I soggetti potenziali beneficiari sono i lavoratori dipendenti del settore sanitario, pubblico e privato accreditato, appartenenti categorie di medici, infermieri, tecnici di laboratorio biomedico, tecnici di radiologia medica, operatori sociosanitari nonch\u00e9 al personale del comparto sicurezza, difesa e soccorso pubblico impiegato per le esigenze connesse all\u2019emergenza epidemiologica da COVID-19.<\/p>\n<p>Con la <a class=\"NormSott\" title=\"Vai alla circolare\" href=\"https:\/\/www.inps.it\/nuovoportaleinps\/default.aspx?sPathID=%3b0%3b52983%3b&amp;lastMenu=52983&amp;iMenu=1&amp;sURL=https%3a%2f%2fwww.inps.it%2fbussola%2fVisualizzaDoc.aspx%3fsVirtualURL%3d%252fCircolari%252fCircolare%2520numero%252047%2520del%252028-03-2020.htm&amp;RedirectForzato=True\" target=\"_blank\" rel=\"noopener noreferrer\">circolare INPS 28 marzo 2020, n.47<\/a>, si illustrano le <strong>misure a sostegno del reddito<\/strong> previste dal decreto-legge n. 18\/2020, per <strong>sospensione o riduzione dell&#8217;attivit\u00e0<\/strong> <strong>lavorativa <\/strong>per eventi riconducibili all&#8217;emergenza epidemiologica da COVID-19, nonch\u00e9 sulla gestione dell\u2019iter concessorio relativo alle medesime misure previste dagli articoli 19, 20, 21 e 22 del citato decreto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il decreto legge 17 marzo 2020, n. 18, cosiddetto \u201cCura Italia\u201d, ha previso misure di sostegno alle famiglie e ai lavoratori, connesse all\u2019emergenza epidemiologica COVID -19.L\u2019articolo 23 del d.l. 18\/2020<\/p>\n","protected":false},"author":3,"featured_media":2181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[316],"tags":[],"class_list":["post-2180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Decreto Cura Italia del 17 marzo 2020, n.18 - FABI VITERBO<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Decreto Cura Italia del 17 marzo 2020, n.18 - FABI VITERBO\" \/>\r\n<meta property=\"og:description\" content=\"Il decreto legge 17 marzo 2020, n. 18, cosiddetto \u201cCura Italia\u201d, ha previso misure di sostegno alle famiglie e ai lavoratori, connesse all\u2019emergenza epidemiologica COVID -19.L\u2019articolo 23 del d.l. 18\/2020\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/\" \/>\r\n<meta property=\"og:site_name\" content=\"FABI VITERBO\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fabivt.it\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-03-30T10:43:25+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2020-04-26T13:08:51+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"600\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\r\n<meta name=\"author\" content=\"Redazione Fabi\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@FABIVITERBO\" \/>\r\n<meta name=\"twitter:site\" content=\"@FABIVITERBO\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione Fabi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/\"},\"author\":{\"name\":\"Redazione Fabi\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/#\/schema\/person\/597a66507fe15fe7bce3508477db1188\"},\"headline\":\"Decreto Cura Italia del 17 marzo 2020, n.18\",\"datePublished\":\"2020-03-30T10:43:25+00:00\",\"dateModified\":\"2020-04-26T13:08:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/\"},\"wordCount\":334,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif\",\"articleSection\":[\"coronavirus\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/\",\"url\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/\",\"name\":\"Decreto Cura Italia del 17 marzo 2020, n.18 - FABI VITERBO\",\"isPartOf\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif\",\"datePublished\":\"2020-03-30T10:43:25+00:00\",\"dateModified\":\"2020-04-26T13:08:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#primaryimage\",\"url\":\"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif\",\"contentUrl\":\"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fabivt.it\/wp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decreto Cura Italia del 17 marzo 2020, n.18\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/#website\",\"url\":\"https:\/\/www.fabivt.it\/wp\/\",\"name\":\"FABI - Federazione autonoma bancari Viterbo\",\"description\":\"Federazione Autonoma Bancari Italiani\",\"publisher\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fabivt.it\/wp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/#organization\",\"name\":\"FABI\",\"url\":\"https:\/\/www.fabivt.it\/wp\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2019\/11\/logo4.png\",\"contentUrl\":\"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2019\/11\/logo4.png\",\"width\":316,\"height\":320,\"caption\":\"FABI\"},\"image\":{\"@id\":\"https:\/\/www.fabivt.it\/wp\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/fabivt.it\",\"https:\/\/x.com\/FABIVITERBO\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/#\/schema\/person\/597a66507fe15fe7bce3508477db1188\",\"name\":\"Redazione Fabi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.fabivt.it\/wp\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2e631c69cdab369cbd1a3c6e2c225f8d8889deea49544ec033021c2235151f9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2e631c69cdab369cbd1a3c6e2c225f8d8889deea49544ec033021c2235151f9b?s=96&d=mm&r=g\",\"caption\":\"Redazione Fabi\"},\"url\":\"https:\/\/www.fabivt.it\/wp\/author\/redazione-fabi\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decreto Cura Italia del 17 marzo 2020, n.18 - FABI VITERBO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/","og_locale":"it_IT","og_type":"article","og_title":"Decreto Cura Italia del 17 marzo 2020, n.18 - FABI VITERBO","og_description":"Il decreto legge 17 marzo 2020, n. 18, cosiddetto \u201cCura Italia\u201d, ha previso misure di sostegno alle famiglie e ai lavoratori, connesse all\u2019emergenza epidemiologica COVID -19.L\u2019articolo 23 del d.l. 18\/2020","og_url":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/","og_site_name":"FABI VITERBO","article_publisher":"https:\/\/www.facebook.com\/fabivt.it","article_published_time":"2020-03-30T10:43:25+00:00","article_modified_time":"2020-04-26T13:08:51+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif","type":"image\/gif"}],"author":"Redazione Fabi","twitter_card":"summary_large_image","twitter_creator":"@FABIVITERBO","twitter_site":"@FABIVITERBO","twitter_misc":{"Scritto da":"Redazione Fabi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#article","isPartOf":{"@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/"},"author":{"name":"Redazione Fabi","@id":"https:\/\/www.fabivt.it\/wp\/#\/schema\/person\/597a66507fe15fe7bce3508477db1188"},"headline":"Decreto Cura Italia del 17 marzo 2020, n.18","datePublished":"2020-03-30T10:43:25+00:00","dateModified":"2020-04-26T13:08:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/"},"wordCount":334,"commentCount":0,"publisher":{"@id":"https:\/\/www.fabivt.it\/wp\/#organization"},"image":{"@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif","articleSection":["coronavirus"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/","url":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/","name":"Decreto Cura Italia del 17 marzo 2020, n.18 - FABI VITERBO","isPartOf":{"@id":"https:\/\/www.fabivt.it\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#primaryimage"},"image":{"@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif","datePublished":"2020-03-30T10:43:25+00:00","dateModified":"2020-04-26T13:08:51+00:00","breadcrumb":{"@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#primaryimage","url":"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif","contentUrl":"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.fabivt.it\/wp\/decreto-cura-italia-del-17-marzo-2020-n-18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fabivt.it\/wp\/"},{"@type":"ListItem","position":2,"name":"Decreto Cura Italia del 17 marzo 2020, n.18"}]},{"@type":"WebSite","@id":"https:\/\/www.fabivt.it\/wp\/#website","url":"https:\/\/www.fabivt.it\/wp\/","name":"FABI - Federazione autonoma bancari Viterbo","description":"Federazione Autonoma Bancari Italiani","publisher":{"@id":"https:\/\/www.fabivt.it\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fabivt.it\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.fabivt.it\/wp\/#organization","name":"FABI","url":"https:\/\/www.fabivt.it\/wp\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fabivt.it\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2019\/11\/logo4.png","contentUrl":"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2019\/11\/logo4.png","width":316,"height":320,"caption":"FABI"},"image":{"@id":"https:\/\/www.fabivt.it\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fabivt.it","https:\/\/x.com\/FABIVITERBO"]},{"@type":"Person","@id":"https:\/\/www.fabivt.it\/wp\/#\/schema\/person\/597a66507fe15fe7bce3508477db1188","name":"Redazione Fabi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.fabivt.it\/wp\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2e631c69cdab369cbd1a3c6e2c225f8d8889deea49544ec033021c2235151f9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e631c69cdab369cbd1a3c6e2c225f8d8889deea49544ec033021c2235151f9b?s=96&d=mm&r=g","caption":"Redazione Fabi"},"url":"https:\/\/www.fabivt.it\/wp\/author\/redazione-fabi\/"}]}},"jetpack_featured_media_url":"https:\/\/www.fabivt.it\/wp\/wp-content\/uploads\/2020\/03\/visual_decreto_curaItalia.gif","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/posts\/2180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/comments?post=2180"}],"version-history":[{"count":4,"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/posts\/2180\/revisions"}],"predecessor-version":[{"id":2185,"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/posts\/2180\/revisions\/2185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/media\/2181"}],"wp:attachment":[{"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/media?parent=2180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/categories?post=2180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fabivt.it\/wp\/wp-json\/wp\/v2\/tags?post=2180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}